{"id":2732,"date":"2026-06-09T18:21:18","date_gmt":"2026-06-09T09:21:18","guid":{"rendered":"https:\/\/xb436991.xbiz.jp\/senshunkai_corporate_version2\/?post_type=news&#038;p=2732"},"modified":"2026-06-30T15:21:19","modified_gmt":"2026-06-30T06:21:19","slug":"%e4%bb%a4%e5%92%8c8%e5%b9%b46%e6%9c%8827%e6%97%a5%ef%bc%88%e5%9c%9f%ef%bc%89%e3%80%8efukushi-%e5%b0%b1%e8%81%b7%e3%83%95%e3%82%a7%e3%82%a2kyoto%e3%80%8f%e3%81%ab%e5%87%ba%e5%b1%95%e3%81%97%e3%81%be","status":"publish","type":"news","link":"https:\/\/xb436991.xbiz.jp\/senshunkai_corporate_version2\/news\/%e4%bb%a4%e5%92%8c8%e5%b9%b46%e6%9c%8827%e6%97%a5%ef%bc%88%e5%9c%9f%ef%bc%89%e3%80%8efukushi-%e5%b0%b1%e8%81%b7%e3%83%95%e3%82%a7%e3%82%a2kyoto%e3%80%8f%e3%81%ab%e5%87%ba%e5%b1%95%e3%81%97%e3%81%be\/","title":{"rendered":"\u4ee4\u548c8\u5e746\u670827\u65e5\uff08\u571f\uff09\u300eFUKUSHI \u5c31\u8077\u30d5\u30a7\u30a2KYOTO\u300f\u306b\u51fa\u5c55\u3057\u307e\u3059\uff08\u4f1a\u5834\uff1a\u307f\u3084\u3053\u3081\u3063\u305b\uff09"},"content":{"rendered":"","protected":false},"featured_media":0,"parent":0,"template":"","meta":{"_acf_changed":false},"news_cat":[42],"class_list":["post-2732","news","type-news","status-publish","hentry","news_cat-care"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/xb436991.xbiz.jp\/senshunkai_corporate_version2\/wp-json\/wp\/v2\/news\/2732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xb436991.xbiz.jp\/senshunkai_corporate_version2\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/xb436991.xbiz.jp\/senshunkai_corporate_version2\/wp-json\/wp\/v2\/types\/news"}],"wp:attachment":[{"href":"https:\/\/xb436991.xbiz.jp\/senshunkai_corporate_version2\/wp-json\/wp\/v2\/media?parent=2732"}],"wp:term":[{"taxonomy":"news_cat","embeddable":true,"href":"https:\/\/xb436991.xbiz.jp\/senshunkai_corporate_version2\/wp-json\/wp\/v2\/news_cat?post=2732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}